{"id":21881,"date":"2025-10-06T16:58:00","date_gmt":"2025-10-06T14:58:00","guid":{"rendered":"https:\/\/www.monapart.com\/magazine\/?p=21881"},"modified":"2026-07-15T12:51:51","modified_gmt":"2026-07-15T10:51:51","slug":"mikel-iturriaga","status":"publish","type":"post","link":"https:\/\/www.monapart.com\/magazine\/ca\/hogar\/mikel-iturriaga","title":{"rendered":"Mikel Iturriaga: la gastronom\u00eda como forma de estar en casa"},"content":{"rendered":"<h1 class=\"wp-block-heading\"><strong>Mikel Iturriaga: la gastronom\u00eda como forma de estar en casa<\/strong><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Una conversaci\u00f3n con el periodista gastron\u00f3mico sobre  cocinas peque\u00f1as, recetas tradicionales y por qu\u00e9 el ruido de coches es su l\u00ednea roja<\/h2>\n\n\n<div class='post-info'>6 d'octubre de 2025 por <a href='https:\/\/www.monapart.com\/magazine\/ca\/autor\/claudia-romero'>Claudia Romero<\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"class-h3\">Mikel Iturriaga es periodista gastron\u00f3mico, autor del blog Con las manos en la masa y de varios libros de cocina, el \u00faltimo de ellos <em>Cocina de aqu\u00ed para gente de hoy<\/em>. Lleg\u00f3 al periodismo gastron\u00f3mico casi por casualidad \u2014estudi\u00f3 Filolog\u00eda Hisp\u00e1nica y pas\u00f3 antes por el periodismo musical y el digital\u2014 pero lleva a\u00f1os siendo una de las voces m\u00e1s queridas a la hora de rescatar <a href=\"https:\/\/www.monapart.com\/magazine\/ca\/llar\/parmentiers\/\">recetas tradicionales espa\u00f1olas<\/a> y contarlas a un p\u00fablico nuevo. Hoy le hemos pedido que baje la guardia y nos hable de su casa: de lo que huele, de lo que suena, de lo que no negocia y de lo que se comprar\u00eda ma\u00f1ana mismo si pudiera.<\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-1-1024x819.png\" alt=\"Mikel Iturriaga: la gastronom\u00eda como forma de estar en casa | Monapart\" class=\"wp-image-21882\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-1-1024x819.png 1024w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-1-300x240.png 300w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-1-768x614.png 768w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-1-15x12.png 15w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-1.png 1350w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a9Becky Lawton<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1l es la primera palabra que te viene a la cabeza cuando piensas en casa?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Iba a decir seguridad o paz, pero siendo sincero la palabra es sof\u00e1. Tumbarme en el sof\u00e1 es una actividad a la que dedico, \u00abmucho esfuerzo\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 olor o sonido te hace sentir en casa al instante?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El olor a cebolla poch\u00e1ndose en la sart\u00e9n. Es el arranque de muchos de mis platos, y tambi\u00e9n el olor que asocio a sentirme seguro, tranquilo y bien en mi propia casa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1l es el factor no negociable para ti al elegir un lugar para vivir?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Que sea tranquilo. No podr\u00eda vivir en una calle con mucho ruido de coches y tr\u00e1fico; si no me quedara m\u00e1s remedio lo har\u00eda, pero pudiendo elegir, prefiero quedarme fuera de eso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un pla a casa sempre inclou\u2026<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Comida, \u00abpara sorpresa de nadie\u00bb. Buenos platos, buenos aperitivos, buenas bebidas. Nada demasiado complicado ni rebuscado, pero cosas que est\u00e9n ricas y que alegren la vida.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/rin-ran-cazorla-1024x768.jpeg\" alt=\"Mikel Iturriaga: la gastronom\u00eda como forma de estar en casa | Monapart\" class=\"wp-image-21883\" style=\"width:640px;height:auto\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/rin-ran-cazorla-1024x768.jpeg 1024w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/rin-ran-cazorla-300x225.jpeg 300w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/rin-ran-cazorla-768x576.jpeg 768w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/rin-ran-cazorla-1536x1152.jpeg 1536w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/rin-ran-cazorla-2048x1536.jpeg 2048w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/rin-ran-cazorla-16x12.jpeg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 canci\u00f3n escuchas en bucle \u00faltimamente en casa?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No suelo escuchar canciones en bucle \u2014intento dosificarme\u2014, pero ahora mismo tiene enganchada <em>What Was That<\/em>, del \u00faltimo disco de Lorde.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 objeto de tu casa dir\u00edas que es muy t\u00fa? \u00bfPor qu\u00e9 te identificas con \u00e9l?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mi \u00faltimo libro, <em>Cocina de aqu\u00ed para gente de hoy<\/em> \u2014y as\u00ed meto la ficha promocional,\u2014, y un mu\u00f1equito de Greta, la gremlin travesti: \u00abmuy gay, muy buena en el fondo y muy sexy, como yo\u00bb.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-2-1024x819.png\" alt=\"Mikel Iturriaga: la gastronom\u00eda como forma de estar en casa | Monapart\" class=\"wp-image-21888\" style=\"aspect-ratio:1.25033246786144;width:669px;height:auto\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-2-1024x819.png 1024w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-2-300x240.png 300w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-2-768x614.png 768w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-2-15x12.png 15w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Copia-de-Fotos-Magazine-2.png 1350w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Si pudieras comprarte cualquier cosa ahora mismo para tu casa, \u00bfqu\u00e9 ser\u00eda?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El piso de al lado, para hacerme una cocina gigante. La que tengo ahora se me queda un poco peque\u00f1a. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/cocina-1-768x1024.jpeg\" alt=\"Mikel Iturriaga: la gastronom\u00eda como forma de estar en casa | Monapart\" class=\"wp-image-21889\" style=\"width:512px;height:auto\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/cocina-1-768x1024.jpeg 768w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/cocina-1-225x300.jpeg 225w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/cocina-1-1152x1536.jpeg 1152w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/cocina-1-1536x2048.jpeg 1536w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/cocina-1-9x12.jpeg 9w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/cocina-1-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo te imaginas la casa del futuro?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mi yo optimista se la imagina m\u00e1s tecnificada que la de ahora, pero acogedora, c\u00f3moda y bonita. Mi yo pesimista, en cambio, temo una casa tan minimalista que la cocina pr\u00e1cticamente haya desaparecido: \u00ablo cual es un aut\u00e9ntico drama\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Parla&#039;ns de tu i de la teva feina. On va n\u00e9ixer la teva vocaci\u00f3?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Estudi\u00e9 Filolog\u00eda Hisp\u00e1nica y llegu\u00e9 al periodismo casi de rebote, cuando alguien me habl\u00f3 de un m\u00e1ster en El Pa\u00eds. La gastronom\u00eda lleg\u00f3 despu\u00e9s, tras una temporada en paro, cuando vi un hueco para hacer algo distinto en un terreno que ya le interesaba desde antes. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abPoca vocaci\u00f3n, pero al final he encontrado una disciplina dentro del periodismo que me gusta y con la que disfruto mucho\u00bb.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qu\u00e8 \u00e9s el que m\u00e9s et satisf\u00e0 de la teva feina?<\/strong><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/estanteria-768x1024.jpeg\" alt=\"Mikel Iturriaga: la gastronom\u00eda como forma de estar en casa | Monapart\" class=\"wp-image-21894\" style=\"width:292px;height:auto\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/estanteria-768x1024.jpeg 768w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/estanteria-225x300.jpeg 225w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/estanteria-1152x1536.jpeg 1152w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/estanteria-1536x2048.jpeg 1536w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/estanteria-9x12.jpeg 9w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/estanteria-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Dos cosas. Una, descubrir recetas tradicionales espa\u00f1olas poco conocidas fuera de su lugar de origen y darlas a conocer a un p\u00fablico m\u00e1s joven o m\u00e1s amplio \u2014el motor de mi \u00faltimo libro\u2014. La otra, que alguien me diga que ha cocinado un plato m\u00edo, ha descubierto un restaurante o un producto gracias a m\u00ed y le ha gustado. Eso da mucho gustito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qu\u00e8 us inspira?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los libros de cocina, de autores grandes y peque\u00f1os, nuevos y viejos. Tambi\u00e9n las redes sociales que, pese a tener \u00abmuch\u00edsimas cosas malas\u00bb y ser \u00abbastante atroces y malignas\u00bb, esconden un lado bueno: permiten descubrir el trabajo de mucha gente, y hay muy buena cocina si se sabe buscar. Para los art\u00edculos y reportajes, en cambio, tiro de lecturas variadas: internet, libros, prensa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Color, libro y peli favoritos, \u00a1por este orden!<\/strong><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Plantilla-entrevista-Magazine-1024x819.png\" alt=\"Mikel Iturriaga: la gastronom\u00eda como forma de estar en casa | Monapart\" class=\"wp-image-21895\" style=\"width:460px;height:auto\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Plantilla-entrevista-Magazine-1024x819.png 1024w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Plantilla-entrevista-Magazine-300x240.png 300w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Plantilla-entrevista-Magazine-768x614.png 768w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Plantilla-entrevista-Magazine-15x12.png 15w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2026\/07\/Plantilla-entrevista-Magazine.png 1350w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"class-h3\">Entre cebollas poch\u00e1ndose y una cocina que sue\u00f1a con ser m\u00e1s grande, <a href=\"https:\/\/www.instagram.com\/mikeliturriaga\/?hl=es\" target=\"_blank\" rel=\"noopener\">Mikel Iturriaga<\/a> nos recuerda que el hogar, como una buena receta tradicional, no necesita artificios: solo ingredientes honestos, tiempo y ganas de compartirlo con quien se sienta a la mesa.<br><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>","protected":false},"excerpt":{"rendered":"<p>Una conversaci\u00f3n con Mikel Iturriaga: el periodista gastron\u00f3mico sobre sof\u00e1s, cocinas peque\u00f1as, recetas tradicionales y por qu\u00e9 el ruido de coches es su l\u00ednea roja.<\/p>","protected":false},"author":11,"featured_media":21882,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2844,2845],"tags":[2889],"class_list":["post-21881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar","category-mi-monapart","tag-cocina"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/posts\/21881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/comments?post=21881"}],"version-history":[{"count":15,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/posts\/21881\/revisions"}],"predecessor-version":[{"id":21937,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/posts\/21881\/revisions\/21937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/media\/21882"}],"wp:attachment":[{"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/media?parent=21881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/categories?post=21881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/tags?post=21881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}