{"id":18154,"date":"2025-05-19T17:44:14","date_gmt":"2025-05-19T15:44:14","guid":{"rendered":"https:\/\/www.monapart.com\/magazine\/?p=18154"},"modified":"2026-06-09T11:41:47","modified_gmt":"2026-06-09T09:41:47","slug":"marset-la-llum-que-es-dissenya","status":"publish","type":"post","link":"https:\/\/www.monapart.com\/magazine\/ca\/hogar\/marset-la-luz-que-se-disena","title":{"rendered":"Marset: la llum que es pensa, es dissenya i se sent"},"content":{"rendered":"<h1 class=\"wp-block-heading\">Marset: la llum que es pensa, es dissenya i se sent<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Dissenyar llums per il\u00b7luminar millor la vida. Aix\u00ed \u00e9s Marset, la marca catalana que converteix la llum en emoci\u00f3, disseny i comprom\u00eds.<\/h2>\n\n\n<div class='post-info'>19 de maig de 2025 por <a href='https:\/\/www.monapart.com\/magazine\/ca\/autor\/claudia-romero'>Claudia Romero<\/a><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"517\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/marset-iluminacion-2-1607509976-1-copia-1024x517.png\" alt=\"Marset: la llum que es pensa, es dissenya i se sent | Monapart\" class=\"wp-image-20255\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/marset-iluminacion-2-1607509976-1-copia-1024x517.png 1024w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/marset-iluminacion-2-1607509976-1-copia-300x152.png 300w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/marset-iluminacion-2-1607509976-1-copia-768x388.png 768w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/marset-iluminacion-2-1607509976-1-copia-1536x776.png 1536w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/marset-iluminacion-2-1607509976-1-copia-2048x1035.png 2048w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/marset-iluminacion-2-1607509976-1-copia-18x9.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Dipping Light de&nbsp;Jordi Canudas, 2018<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Marset es una de esas marcas que ha sabido crecer desde lo industrial hacia lo emocional, sin perder el rumbo. Naci\u00f3 en Barcelona a mediados del siglo XX como una peque\u00f1a fundici\u00f3n de metales, pero su evoluci\u00f3n la ha convertido en uno de los grandes referentes internacionales del dise\u00f1o de iluminaci\u00f3n. Hoy, desde su sede en Terrassa, dise\u00f1a y fabrica <a href=\"https:\/\/www.monapart.com\/magazine\/ca\/etiquetes\/il%c2%b7luminacio\/\">llums<\/a> que no solo iluminan espacios, sino que los transforman.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carlos Marset, juntament amb el seu germ\u00e0 Javier, forma part de la tercera generaci\u00f3 al capdavant de l?empresa. El seu enfocament \u00e9s clar: crear peces que combinin bellesa, funcionalitat i sostenibilitat. Perqu\u00e8 a Marset no es dissenyen llums nom\u00e9s perqu\u00e8 siguin boniques, sin\u00f3 perqu\u00e8 ajudin a viure millor.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Copia-de-Fotos-Magazine-5-1-1024x819.png\" alt=\"Marset: la llum que es pensa, es dissenya i se sent | Monapart\" class=\"wp-image-20260\" style=\"aspect-ratio:1.2503197897527734;width:729px;height:auto\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Copia-de-Fotos-Magazine-5-1-1024x819.png 1024w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Copia-de-Fotos-Magazine-5-1-300x240.png 300w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Copia-de-Fotos-Magazine-5-1-768x614.png 768w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Copia-de-Fotos-Magazine-5-1-15x12.png 15w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Copia-de-Fotos-Magazine-5-1.png 1350w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Carlos y Javier Marset<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Una de las claves del \u00e9xito de <a href=\"https:\/\/www.instagram.com\/marsetbcn\/\" rel=\"nofollow noopener\" target=\"_blank\">Marset<\/a> es el equilibrio entre tradici\u00f3n e innovaci\u00f3n. A lo largo de los a\u00f1os, han colaborado con dise\u00f1adores como Joan Gaspar, Inma Berm\u00fadez o Jordi Canudas para dar forma a piezas que ya son iconos, como la FollowMe, la Ginger o la Dipping Light. L\u00e1mparas port\u00e1tiles, ligeras, con tecnolog\u00eda LED y bater\u00edas recargables, que han sido reconocidas internacionalmente y expuestas en lugares como el MoMA de Nueva York o el Centro Pompidou de Par\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"618\" height=\"412\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Marset-showroom-en-Nueva-York.jpg\" alt=\"Marset: la llum que es pensa, es dissenya i se sent | Monapart\" class=\"wp-image-20141\" style=\"aspect-ratio:1.5000189630978116;width:840px;height:auto\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Marset-showroom-en-Nueva-York.jpg 618w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Marset-showroom-en-Nueva-York-300x200.jpg 300w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Marset-showroom-en-Nueva-York-18x12.jpg 18w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><figcaption class=\"wp-element-caption\">Showroom de Marset en Nueva York<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><br>La nova seu de la marca, situada a una antiga f\u00e0brica rehabilitada a Terrassa, \u00e9s una declaraci\u00f3 d?intencions. All\u00e0 es combinen oficines, showroom, magatzem i centre log\u00edstic. Un espai funcional, s\u00ed, per\u00f2 tamb\u00e9 dissenyat amb cura, com si fos una de les seves pr\u00f2pies l\u00e0mpades. Tot est\u00e0 pensat perqu\u00e8 el dia a dia de l&#039;empresa en reflecteixi els valors: rigor, cura del detall, comprom\u00eds amb el medi ambient i respecte pel disseny com una eina per millorar la vida.<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-8f761849 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\">Marset exporta sus productos a m\u00e1s de 40 pa\u00edses y est\u00e1 presente en proyectos internacionales de primer nivel: hoteles como el Virgin Hotel de Chicago, oficinas como la de Sony en Madrid, o cafeter\u00edas como Starbucks en Nueva York. Sin embargo, no ha perdido el car\u00e1cter cercano de una empresa familiar. Como explicaba Javier Marset en una entrevista reciente.<\/p>\n<\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>\u201cNo ens interessa fer soroll, ens interessa perdurar\u201d.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">L&#039;enfocament de la marca cap a la sostenibilitat tamb\u00e9 \u00e9s clar. Utilitzen materials duradors, minimitzen residus i aposten per processos de fabricaci\u00f3 responsables. Tot aix\u00f2 sense renunciar a la tecnologia ni al disseny m\u00e9s avan\u00e7at. Perqu\u00e8, com diuen ells mateixos, \u201cla sostenibilitat no \u00e9s una opci\u00f3, \u00e9s una obligaci\u00f3\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Collage-de-Fotos-Cuadricula-Lifestyle-Minimalista-Gris-1024x819.png\" alt=\"Marset: la llum que es pensa, es dissenya i se sent | Monapart\" class=\"wp-image-21443\" srcset=\"https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Collage-de-Fotos-Cuadricula-Lifestyle-Minimalista-Gris-1024x819.png 1024w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Collage-de-Fotos-Cuadricula-Lifestyle-Minimalista-Gris-300x240.png 300w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Collage-de-Fotos-Cuadricula-Lifestyle-Minimalista-Gris-768x614.png 768w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Collage-de-Fotos-Cuadricula-Lifestyle-Minimalista-Gris-1536x1229.png 1536w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Collage-de-Fotos-Cuadricula-Lifestyle-Minimalista-Gris-15x12.png 15w, https:\/\/www.monapart.com\/magazine\/wp-content\/uploads\/2025\/05\/Collage-de-Fotos-Cuadricula-Lifestyle-Minimalista-Gris.png 1750w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">I \u00e9s que la llum a Marset no s&#039;ent\u00e9n com una funci\u00f3 sin\u00f3 com una experi\u00e8ncia. Cada llum explica una hist\u00f2ria, genera una atmosfera i contribueix a crear llars m\u00e9s agradables, m\u00e9s humanes. Per aix\u00f2, els seus productes no segueixen modes, sin\u00f3 que aposten per l&#039;atemporalitat. L\u00e0mpades que no cansen, que s&#039;integren i que acompanyen durant anys.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Dissenyar llums per il\u00b7luminar millor la vida. Aix\u00ed \u00e9s Marset, la marca catalana que converteix la llum en emoci\u00f3, disseny i comprom\u00eds.<\/p>","protected":false},"author":11,"featured_media":20256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2844,2846],"tags":[3261],"class_list":["post-18154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar","category-espacios-y-vida","tag-iluminacion"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/posts\/18154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/comments?post=18154"}],"version-history":[{"count":28,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/posts\/18154\/revisions"}],"predecessor-version":[{"id":21476,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/posts\/18154\/revisions\/21476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/media\/20256"}],"wp:attachment":[{"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/media?parent=18154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/categories?post=18154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monapart.com\/magazine\/ca\/wp-json\/wp\/v2\/tags?post=18154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}